{"id":4983,"date":"2022-01-12T16:53:03","date_gmt":"2022-01-12T15:53:03","guid":{"rendered":"https:\/\/www.consorziogrifone.com\/resincondotte-s-r-l\/"},"modified":"2024-06-25T13:20:06","modified_gmt":"2024-06-25T12:20:06","slug":"resincondotte-s-r-l","status":"publish","type":"page","link":"https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/resincondotte-s-r-l\/","title":{"rendered":"Resincondotte S.r.l."},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-8-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-8%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#2158A5&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;box-top-socio&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;5432&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_custom_heading text=&#8221;Resincondotte S.r.l.&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221;][vc_custom_heading text=&#8221;Specialists in trading pipes and fittings since 1975&#8243; font_container=&#8221;tag:h3|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221;]\n<p class=\"p1\"><b>Founded in 1975<\/b>, <b>Resincondotte S.r.l.<\/b> specialises in <b>trading pipes and fittings for water systems, sewers, gas pipelines, industry, thermohydraulics and irrigation.<\/b><\/p>\n<p class=\"p1\">One of the company&#8217;s primary objectives has always been to supply products that are reliable and safe. This is also why the company obtained UNI EN ISO 9002 (which later became <b>UNI EN ISO 9001:2015<\/b>) certification.<\/p>\n<p class=\"p1\">Resincondotte <b>was one of the founders of the Consorzio Stabile Grifone<\/b> in <b>1997<\/b>.<\/p>\n<p class=\"p1\">In addition to its head office in Moncalieri (TO), Resincondotte also has a <b>branch in Brissogne<\/b>, in the Aosta Valley, and is able to produce <b>special pieces<\/b> to design, while also organising <b>courses on the design of irrigation systems<\/b> and the <b>qualification<\/b> of <b>welders<\/b>.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#edf1f4&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;sgvs-blue-large right&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#ffffff&#8221; shape_divider_position=&#8221;both&#8221; shape_divider_height=&#8221;300&#8243; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;straight_section&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;6\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_image_with_hotspots image=&#8221;5348&#8243; preview=&#8221;https:\/\/www.consorziogrifone.com\/wp-content\/uploads\/2022\/11\/italia.png&#8221; color_1=&#8221;Accent-Color&#8221; hotspot_icon=&#8221;plus_sign&#8221; tooltip=&#8221;click&#8221; tooltip_shadow=&#8221;none&#8221;][nectar_hotspot left=&#8221;6.08035%&#8221; top=&#8221;17.4997%&#8221; position=&#8221;top&#8221;]<b>Resincondotte S.r.l.<\/b> <strong>Operational headquarters:<\/strong> Viale Europa, 60 \u2013 10024 Moncalieri (TO) \u2013 <a href=\"tel:+390112261661\">011 2261661<\/a>[\/nectar_hotspot][nectar_hotspot left=&#8221;1.9544%&#8221; top=&#8221;9.42097%&#8221; position=&#8221;top&#8221;]<b>Resincondotte S.r.l.<\/b> <strong>Branch<\/strong>: Loc. Les Illes, 11 \u2013 11020 Brissogne (AO) \u2013 <a href=\"tel:+3900165762067\">0165 762067<\/a>[\/nectar_hotspot][\/nectar_image_with_hotspots][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; class=&#8221;box-contatti-partner&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-15-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-20%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#439cd6&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Resincondotte S.r.l.&#8221; font_container=&#8221;tag:h2|text_align:left|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1645612093255{margin-bottom: 20px !important;}&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-map-marker extra-color-3\"><\/i> <\/div><div class=\"iwt-text\"> Viale Europa, 60 \u2013 10024 Moncalieri (TO) <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-phone extra-color-3\"><\/i> <\/div><div class=\"iwt-text\"> <a href=\"tel:+390112261661\">+39 011 2261661<\/a> <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-envelope extra-color-3\"><\/i> <\/div><div class=\"iwt-text\"> <a href=\"mailto:resincondotte@resincondotte.it\"> resincondotte@resincondotte.it <\/a><br \/>\n<a href=\"mailto:aosta@resincondotte.it\"> aosta@resincondotte.it <\/a> <\/div><div class=\"clear\"><\/div><\/div><div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-link extra-color-3\"><\/i> <\/div><div class=\"iwt-text\"> <a href=\"https:\/\/www.resincondotte.it\/\" target=\"_blank\" rel=\"noopener\">www.resincondotte.it<\/a> <\/div><div class=\"clear\"><\/div><\/div>[divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;white&#8221;][nectar_cta btn_style=&#8221;arrow-animation&#8221; heading_tag=&#8221;h6&#8243; button_color=&#8221;default&#8221; text_color=&#8221;#ffffff&#8221; button_border_thickness=&#8221;0px&#8221; link_type=&#8221;regular&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;Write to&#8221; margin_top=&#8221;40&#8243; class=&#8221;btn-contact-socio&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;4061&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_gallery type=&#8221;flickity_style&#8221; images=&#8221;4015,4016,4017,4018&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;pagination&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_desktop_columns=&#8221;3&#8243; flickity_small_desktop_columns=&#8221;2&#8243; flickity_tablet_columns=&#8221;1&#8243; flickity_phone_columns=&#8221;1&#8243; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-8-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-8%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":5051,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[94],"tags":[],"class_list":["post-4983","page","type-page","status-publish","category-members"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tube trade<\/title>\n<meta name=\"description\" content=\"Resincondotte Srl is specialized in the trade of pipes and fittings for aqueducts, sewers, gas pipelines, thermo-hydraulic and irrigation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/resincondotte-s-r-l\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tube trade\" \/>\n<meta property=\"og:description\" content=\"Resincondotte Srl is specialized in the trade of pipes and fittings for aqueducts, sewers, gas pipelines, thermo-hydraulic and irrigation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/resincondotte-s-r-l\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorzio Stabile Grifone\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-25T12:20:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/members-consorzio\\\/resincondotte-s-r-l\\\/\",\"url\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/members-consorzio\\\/resincondotte-s-r-l\\\/\",\"name\":\"Tube trade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/#website\"},\"datePublished\":\"2022-01-12T15:53:03+00:00\",\"dateModified\":\"2024-06-25T12:20:06+00:00\",\"description\":\"Resincondotte Srl is specialized in the trade of pipes and fittings for aqueducts, sewers, gas pipelines, thermo-hydraulic and irrigation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/members-consorzio\\\/resincondotte-s-r-l\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/members-consorzio\\\/resincondotte-s-r-l\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/members-consorzio\\\/resincondotte-s-r-l\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Members Consorzio\",\"item\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/members-consorzio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Resincondotte S.r.l.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/\",\"name\":\"Consorzio Stabile Grifone\",\"description\":\"Forniture e gestione sottoservizi\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/#organization\",\"name\":\"Consorzio Stabile Grifone\",\"url\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.consorziogrifone.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-color.png\",\"contentUrl\":\"https:\\\/\\\/www.consorziogrifone.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-color.png\",\"width\":426,\"height\":200,\"caption\":\"Consorzio Stabile Grifone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.consorziogrifone.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tube trade","description":"Resincondotte Srl is specialized in the trade of pipes and fittings for aqueducts, sewers, gas pipelines, thermo-hydraulic and irrigation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/resincondotte-s-r-l\/","og_locale":"en_US","og_type":"article","og_title":"Tube trade","og_description":"Resincondotte Srl is specialized in the trade of pipes and fittings for aqueducts, sewers, gas pipelines, thermo-hydraulic and irrigation.","og_url":"https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/resincondotte-s-r-l\/","og_site_name":"Consorzio Stabile Grifone","article_modified_time":"2024-06-25T12:20:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/resincondotte-s-r-l\/","url":"https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/resincondotte-s-r-l\/","name":"Tube trade","isPartOf":{"@id":"https:\/\/www.consorziogrifone.com\/en\/#website"},"datePublished":"2022-01-12T15:53:03+00:00","dateModified":"2024-06-25T12:20:06+00:00","description":"Resincondotte Srl is specialized in the trade of pipes and fittings for aqueducts, sewers, gas pipelines, thermo-hydraulic and irrigation.","breadcrumb":{"@id":"https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/resincondotte-s-r-l\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/resincondotte-s-r-l\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/resincondotte-s-r-l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.consorziogrifone.com\/en\/"},{"@type":"ListItem","position":2,"name":"Members Consorzio","item":"https:\/\/www.consorziogrifone.com\/en\/members-consorzio\/"},{"@type":"ListItem","position":3,"name":"Resincondotte S.r.l."}]},{"@type":"WebSite","@id":"https:\/\/www.consorziogrifone.com\/en\/#website","url":"https:\/\/www.consorziogrifone.com\/en\/","name":"Consorzio Stabile Grifone","description":"Forniture e gestione sottoservizi","publisher":{"@id":"https:\/\/www.consorziogrifone.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consorziogrifone.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.consorziogrifone.com\/en\/#organization","name":"Consorzio Stabile Grifone","url":"https:\/\/www.consorziogrifone.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.consorziogrifone.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.consorziogrifone.com\/wp-content\/uploads\/2022\/01\/logo-color.png","contentUrl":"https:\/\/www.consorziogrifone.com\/wp-content\/uploads\/2022\/01\/logo-color.png","width":426,"height":200,"caption":"Consorzio Stabile Grifone"},"image":{"@id":"https:\/\/www.consorziogrifone.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/pages\/4983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/comments?post=4983"}],"version-history":[{"count":14,"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/pages\/4983\/revisions"}],"predecessor-version":[{"id":5975,"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/pages\/4983\/revisions\/5975"}],"up":[{"embeddable":true,"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/pages\/5051"}],"wp:attachment":[{"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/media?parent=4983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/categories?post=4983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.consorziogrifone.com\/en\/wp-json\/wp\/v2\/tags?post=4983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}